{"id":22,"count":2,"description":"","link":"https:\/\/www.xixentertainment.com\/press\/category\/qviva\/","name":"Q\u2019Viva","slug":"qviva","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.xixentertainment.com\/press\/wp-json\/wp\/v2\/categories\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.xixentertainment.com\/press\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.xixentertainment.com\/press\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.xixentertainment.com\/press\/wp-json\/wp\/v2\/posts?categories=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}